{"id":1918,"date":"2025-07-27T18:00:45","date_gmt":"2025-07-27T11:00:45","guid":{"rendered":"https:\/\/pintarindonesia.com\/?p=1918"},"modified":"2025-07-27T19:28:14","modified_gmt":"2025-07-27T12:28:14","slug":"olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia","status":"publish","type":"post","link":"https:\/\/pintarindonesia.com\/en\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/","title":{"rendered":"Olimpiade FABI 14 Ajang Bergengsi Adu Pengetahuan Anak Indonesia"},"content":{"rendered":"<p><strong>MALANG || PINTAR INDONESIA<\/strong> \u2013 Dalam rangka mencetak anak anak Indonesia menjadi generasi berkualitas, berkarakter dan berwawasan Internasional, Emerald Education Center (EEC) kembali menggelar ajang bergengsi Olimpiade FABI (Festival Anak Berprestasi Indonesia).<\/p>\n<p>Olimpiade FABI event tahunan EEC ini menjadi wadah anak anak hebat Indonesia untuk adu pengetahuan dibidang Match (Matematika), Science (Sains), dan English (Bahasa Inggris).<\/p>\n<p>Olimpiade FABI 14 tahun 2025 kali ini diikuti puluhan ribu peserta dari siswa tingkat SD dan SMP sederajat se- Jawa dan Bali. Namun, yang terseleksi di babak final hanya 5.421 peserta untuk memasuki babak Grand Final yang diselenggarakan pada 26 \u2013 27 Juli 2025 di Universitas Negeri Malang.<\/p>\n<p>Ketua Pelaksana FABI 14, Arif Mustofa menyampaikan bahwa, Olimpiade FABI 14 ini terbagi atas 4 tingkat. Tingkat 1 yakni siswa kelas 1 dan 2 SD\/MI, tingkat 2 siswa kelas 3 dan 4 SD\/MI, tingkat 3 siswa kelas 5 dan 6 SD\/MI, dan tingkat 4 siswa kelas 7 &#8211; 9 SMP\/MTs.<\/p>\n<p>&#8220;Hari ini olimpiade FABI 14 sudah masuk tahap Grand Final. Dimana, peserta saling berkompetisi untuk memperebutkan juara dalam tiap kategori,\u201d ucap Mustofa disela sela acara Awarding Ceremony FABI 14 Minggu, (27\/07\/25) di Universitas Negeri Malang.<\/p>\n<p>Dalam babak Grand Final ini, lanjut Mustofa, merupakan rentetan dari seleksi tingkat kabupaten dan kota se Jawa dan Bali yang telah digelar sebelumnya. Total ada sekitar 5.421 finalis dari berbagai daerah yang telah berpartisipasi dalam FABI 14 di tahun 2025.<\/p>\n<p>&#8220;Setiap tahun selalu ada peningkatan jumlah peserta Olimpiade FABI. Awalnya FABI ini diselenggarakan hanya di Jawa Timur. Namun, tingginya animo peserta diperluas hingga Jawa Bali untuk merebutkan hadiah istimewa. Mulai dari medali, uang pembinaan, hingga field trip ke Singapura,\u201d terangnya.<\/p>\n<p>Hadiah field trip ke luar negeri memang menjadi daya tarik tersendiri bagi peserta. Dengan mengajak para siswa jalan-jalan ke luar negeri, pihak EEC ingin para penerus bangsa ini bisa melihat dan mempelajari budaya serta ekosistem pendidikan yang ada di negara maju.<\/p>\n<p>&#8220;Kita ingin menumbuhkan semangat belajar anak-anak. Jadi kami kasih hadiah ke luar negeri agar mereka bisa melihat bagaimana pendidikan disana,\u201d tandasnya.<\/p>\n<p>Melalui Olimpiade FABI 14 ini, EEC ingin menjadi fasilitator untuk anak anak Indonesia yang ingin menunjukkan kebolehannya di kancah nasional dalam kompetisi matematika, sains dan bahasa Inggris. Sehingga, Indonesia bisa memiliki generasi bangsa yang hebat dan berprestasi.<\/p>\n<p>Dakam kesempatan Awarding Ceremony FABI 14, Mustofa juga menyampaikan selamat bagi para peserta yang menjadi juara. Namun juga memberikan semangat baru bagi peserta yang belum meraih hadiah field trip keluar negeri.<\/p>\n<p>\u201cKalian semua adalah pemenang. Karena, sudah mampu mengikuti semua dengan baik hingga memasuki babak grand final. Tetap semangat dan terus belajar untuk persiapan Olimpiade FABI ke 15 tahun depan,\u201d pungkas Mustofa. (*)<\/p>\n<ul>\n<li><strong>Pewarta<\/strong> : Saputra Wijaya<\/li>\n<li><strong>Foto<\/strong> : Istimewa<\/li>\n<li><strong>Penerbit<\/strong> : Ronie Dwito<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>MALANG || PINTAR INDONESIA \u2013 Dalam rangka mencetak anak anak Indonesia menjadi generasi berkualitas, berkarakter dan berwawasan Internasional,<\/p>\n","protected":false},"author":2,"featured_media":1919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[357,358,356,359],"class_list":["post-1918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nasional","tag-emerald-education-center","tag-festival-anak-berprestasi-indonesia","tag-olimpiade-fabi","tag-universitas-negeri-malang"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Olimpiade FABI 14<\/title>\n<meta name=\"description\" content=\"MALANG || PINTAR INDONESIA \u2013 Dalam rangka mencetak anak anak Indonesia menjadi generasi berkualitas, berkarakter dan berwawasan Internasional, Emerald Education Center (EEC) kembali menggelar ajang bergengsi Olimpiade FABI (Festival Anak Berprestasi Indonesia).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pintarindonesia.com\/en\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olimpiade FABI 14\" \/>\n<meta property=\"og:description\" content=\"MALANG || PINTAR INDONESIA \u2013 Dalam rangka mencetak anak anak Indonesia menjadi generasi berkualitas, berkarakter dan berwawasan Internasional, Emerald Education Center (EEC) kembali menggelar ajang bergengsi Olimpiade FABI (Festival Anak Berprestasi Indonesia).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pintarindonesia.com\/en\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/\" \/>\n<meta property=\"og:site_name\" content=\"Pintar Indonesia\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-27T11:00:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-27T12:28:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1002\" \/>\n\t<meta property=\"og:image:height\" content=\"716\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pintar Indonesia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pintar Indonesia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/\"},\"author\":{\"name\":\"Pintar Indonesia\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#\\\/schema\\\/person\\\/9c07611837d875e39a9dadeb29d70ea8\"},\"headline\":\"Olimpiade FABI 14 Ajang Bergengsi Adu Pengetahuan Anak Indonesia\",\"datePublished\":\"2025-07-27T11:00:45+00:00\",\"dateModified\":\"2025-07-27T12:28:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/\"},\"wordCount\":419,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/pintarindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/FABI-1.jpg?fit=1002%2C716&ssl=1\",\"keywords\":[\"Emerald Education Center\",\"Festival Anak Berprestasi Indonesia\",\"Olimpiade FABI\",\"Universitas Negeri Malang\"],\"articleSection\":[\"Nasional\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/\",\"url\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/\",\"name\":\"Olimpiade FABI 14\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/pintarindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/FABI-1.jpg?fit=1002%2C716&ssl=1\",\"datePublished\":\"2025-07-27T11:00:45+00:00\",\"dateModified\":\"2025-07-27T12:28:14+00:00\",\"description\":\"MALANG || PINTAR INDONESIA \u2013 Dalam rangka mencetak anak anak Indonesia menjadi generasi berkualitas, berkarakter dan berwawasan Internasional, Emerald Education Center (EEC) kembali menggelar ajang bergengsi Olimpiade FABI (Festival Anak Berprestasi Indonesia).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/pintarindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/FABI-1.jpg?fit=1002%2C716&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/pintarindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/FABI-1.jpg?fit=1002%2C716&ssl=1\",\"width\":1002,\"height\":716},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pintarindonesia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Olimpiade FABI 14 Ajang Bergengsi Adu Pengetahuan Anak Indonesia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#website\",\"url\":\"https:\\\/\\\/pintarindonesia.com\\\/\",\"name\":\"Pintar Indonesia\",\"description\":\"Media Terbaik Seputar Pendidikan\",\"publisher\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pintarindonesia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#organization\",\"name\":\"Pintar Indonesia\",\"url\":\"https:\\\/\\\/pintarindonesia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/pintarindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Pintar-Indonesia-Square-Logo-Website.webp?fit=300%2C92&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/pintarindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Pintar-Indonesia-Square-Logo-Website.webp?fit=300%2C92&ssl=1\",\"width\":300,\"height\":92,\"caption\":\"Pintar Indonesia\"},\"image\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#\\\/schema\\\/person\\\/9c07611837d875e39a9dadeb29d70ea8\",\"name\":\"Pintar Indonesia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/752dd16badcd242989572e87eb5db5487d377df186ff99e80148b1aa5f87a1b3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/752dd16badcd242989572e87eb5db5487d377df186ff99e80148b1aa5f87a1b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/752dd16badcd242989572e87eb5db5487d377df186ff99e80148b1aa5f87a1b3?s=96&d=mm&r=g\",\"caption\":\"Pintar Indonesia\"},\"url\":\"https:\\\/\\\/pintarindonesia.com\\\/en\\\/author\\\/tulus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olimpiade FABI 14","description":"MALANG || PINTAR INDONESIA \u2013 Dalam rangka mencetak anak anak Indonesia menjadi generasi berkualitas, berkarakter dan berwawasan Internasional, Emerald Education Center (EEC) kembali menggelar ajang bergengsi Olimpiade FABI (Festival Anak Berprestasi Indonesia).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pintarindonesia.com\/en\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/","og_locale":"en_US","og_type":"article","og_title":"[:id]Olimpiade FABI 14[:]","og_description":"[:id]MALANG || PINTAR INDONESIA \u2013 Dalam rangka mencetak anak anak Indonesia menjadi generasi berkualitas, berkarakter dan berwawasan Internasional, Emerald Education Center (EEC) kembali menggelar ajang bergengsi Olimpiade FABI (Festival Anak Berprestasi Indonesia).[:]","og_url":"https:\/\/pintarindonesia.com\/en\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/","og_site_name":"Pintar Indonesia","article_published_time":"2025-07-27T11:00:45+00:00","article_modified_time":"2025-07-27T12:28:14+00:00","og_image":[{"width":1002,"height":716,"url":"https:\/\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg","type":"image\/jpeg"}],"author":"Pintar Indonesia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Pintar Indonesia","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/#article","isPartOf":{"@id":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/"},"author":{"name":"Pintar Indonesia","@id":"https:\/\/pintarindonesia.com\/#\/schema\/person\/9c07611837d875e39a9dadeb29d70ea8"},"headline":"Olimpiade FABI 14 Ajang Bergengsi Adu Pengetahuan Anak Indonesia","datePublished":"2025-07-27T11:00:45+00:00","dateModified":"2025-07-27T12:28:14+00:00","mainEntityOfPage":{"@id":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/"},"wordCount":419,"commentCount":0,"publisher":{"@id":"https:\/\/pintarindonesia.com\/#organization"},"image":{"@id":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?fit=1002%2C716&ssl=1","keywords":["Emerald Education Center","Festival Anak Berprestasi Indonesia","Olimpiade FABI","Universitas Negeri Malang"],"articleSection":["Nasional"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/","url":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/","name":"Olimpiade FABI 14","isPartOf":{"@id":"https:\/\/pintarindonesia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/#primaryimage"},"image":{"@id":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?fit=1002%2C716&ssl=1","datePublished":"2025-07-27T11:00:45+00:00","dateModified":"2025-07-27T12:28:14+00:00","description":"MALANG || PINTAR INDONESIA \u2013 Dalam rangka mencetak anak anak Indonesia menjadi generasi berkualitas, berkarakter dan berwawasan Internasional, Emerald Education Center (EEC) kembali menggelar ajang bergengsi Olimpiade FABI (Festival Anak Berprestasi Indonesia).","breadcrumb":{"@id":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/#primaryimage","url":"https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?fit=1002%2C716&ssl=1","contentUrl":"https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?fit=1002%2C716&ssl=1","width":1002,"height":716},{"@type":"BreadcrumbList","@id":"https:\/\/pintarindonesia.com\/olimpiade-fabi-14-ajang-bergengsi-adu-pengetahuan-anak-indonesia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pintarindonesia.com\/"},{"@type":"ListItem","position":2,"name":"Olimpiade FABI 14 Ajang Bergengsi Adu Pengetahuan Anak Indonesia"}]},{"@type":"WebSite","@id":"https:\/\/pintarindonesia.com\/#website","url":"https:\/\/pintarindonesia.com\/","name":"Pintar Indonesia","description":"Media Terbaik Seputar Pendidikan","publisher":{"@id":"https:\/\/pintarindonesia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pintarindonesia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pintarindonesia.com\/#organization","name":"Pintar Indonesia","url":"https:\/\/pintarindonesia.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pintarindonesia.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/05\/Pintar-Indonesia-Square-Logo-Website.webp?fit=300%2C92&ssl=1","contentUrl":"https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/05\/Pintar-Indonesia-Square-Logo-Website.webp?fit=300%2C92&ssl=1","width":300,"height":92,"caption":"Pintar Indonesia"},"image":{"@id":"https:\/\/pintarindonesia.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pintarindonesia.com\/#\/schema\/person\/9c07611837d875e39a9dadeb29d70ea8","name":"Pintar Indonesia","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/752dd16badcd242989572e87eb5db5487d377df186ff99e80148b1aa5f87a1b3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/752dd16badcd242989572e87eb5db5487d377df186ff99e80148b1aa5f87a1b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/752dd16badcd242989572e87eb5db5487d377df186ff99e80148b1aa5f87a1b3?s=96&d=mm&r=g","caption":"Pintar Indonesia"},"url":"https:\/\/pintarindonesia.com\/en\/author\/tulus\/"}]}},"featured_image_urls":{"full":["https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?fit=1002%2C716&ssl=1",1002,716,false],"thumbnail":["https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?fit=300%2C214&ssl=1",300,214,true],"medium_large":["https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?fit=640%2C458&ssl=1",640,458,true],"large":["https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?fit=640%2C457&ssl=1",640,457,true],"1536x1536":["https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?fit=1002%2C716&ssl=1",1002,716,true],"2048x2048":["https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?fit=1002%2C716&ssl=1",1002,716,true],"morenews-large":["https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?resize=825%2C575&ssl=1",825,575,true],"morenews-medium":["https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/07\/FABI-1.jpg?resize=590%2C410&ssl=1",590,410,true]},"author_info":{"display_name":"Pintar Indonesia","author_link":"https:\/\/pintarindonesia.com\/en\/author\/tulus\/"},"category_info":"<a href=\"https:\/\/pintarindonesia.com\/en\/category\/nasional\/\" rel=\"category tag\">Nasional<\/a>","tag_info":"Nasional","comment_count":0,"_links":{"self":[{"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/posts\/1918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/comments?post=1918"}],"version-history":[{"count":1,"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/posts\/1918\/revisions"}],"predecessor-version":[{"id":1920,"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/posts\/1918\/revisions\/1920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/media\/1919"}],"wp:attachment":[{"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/media?parent=1918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/categories?post=1918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/tags?post=1918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}