{"id":16,"count":1,"description":"","link":"https:\/\/pintarindonesia.com\/en\/tag\/hyrox-challenge\/","name":"Hyrox Challenge","slug":"hyrox-challenge","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hyrox Challenge Archives - Pintar Indonesia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pintarindonesia.com\/en\/tag\/hyrox-challenge\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:locale:alternate\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hyrox Challenge Archives - Pintar Indonesia\" \/>\n<meta property=\"og:site_name\" content=\"Pintar Indonesia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/tag\\\/hyrox-challenge\\\/\",\"url\":\"https:\\\/\\\/pintarindonesia.com\\\/tag\\\/hyrox-challenge\\\/\",\"name\":\"Hyrox Challenge Archives - Pintar Indonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/tag\\\/hyrox-challenge\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/tag\\\/hyrox-challenge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pintarindonesia.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hyrox Challenge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#website\",\"url\":\"https:\\\/\\\/pintarindonesia.com\\\/\",\"name\":\"Pintar Indonesia\",\"description\":\"Media Terbaik Seputar Pendidikan\",\"publisher\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pintarindonesia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#organization\",\"name\":\"Pintar Indonesia\",\"url\":\"https:\\\/\\\/pintarindonesia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/pintarindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Pintar-Indonesia-Square-Logo-Website.webp?fit=300%2C92&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/pintarindonesia.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Pintar-Indonesia-Square-Logo-Website.webp?fit=300%2C92&ssl=1\",\"width\":300,\"height\":92,\"caption\":\"Pintar Indonesia\"},\"image\":{\"@id\":\"https:\\\/\\\/pintarindonesia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hyrox Challenge Archives - Pintar Indonesia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pintarindonesia.com\/en\/tag\/hyrox-challenge\/","og_locale":"en_US","og_type":"article","og_title":"Hyrox Challenge Archives - Pintar Indonesia","og_site_name":"Pintar Indonesia","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pintarindonesia.com\/tag\/hyrox-challenge\/","url":"https:\/\/pintarindonesia.com\/tag\/hyrox-challenge\/","name":"Hyrox Challenge Archives - Pintar Indonesia","isPartOf":{"@id":"https:\/\/pintarindonesia.com\/#website"},"breadcrumb":{"@id":"https:\/\/pintarindonesia.com\/tag\/hyrox-challenge\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/pintarindonesia.com\/tag\/hyrox-challenge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pintarindonesia.com\/"},{"@type":"ListItem","position":2,"name":"Hyrox Challenge"}]},{"@type":"WebSite","@id":"https:\/\/pintarindonesia.com\/#website","url":"https:\/\/pintarindonesia.com\/","name":"Pintar Indonesia","description":"Media Terbaik Seputar Pendidikan","publisher":{"@id":"https:\/\/pintarindonesia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pintarindonesia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pintarindonesia.com\/#organization","name":"Pintar Indonesia","url":"https:\/\/pintarindonesia.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pintarindonesia.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/05\/Pintar-Indonesia-Square-Logo-Website.webp?fit=300%2C92&ssl=1","contentUrl":"https:\/\/i0.wp.com\/pintarindonesia.com\/wp-content\/uploads\/2025\/05\/Pintar-Indonesia-Square-Logo-Website.webp?fit=300%2C92&ssl=1","width":300,"height":92,"caption":"Pintar Indonesia"},"image":{"@id":"https:\/\/pintarindonesia.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/tags\/16","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/pintarindonesia.com\/en\/wp-json\/wp\/v2\/posts?tags=16"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}